{"id":2419,"date":"2023-07-27T15:26:44","date_gmt":"2023-07-27T13:26:44","guid":{"rendered":"https:\/\/motorshow.lu\/?p=2419"},"modified":"2023-07-27T15:26:45","modified_gmt":"2023-07-27T13:26:45","slug":"merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen","status":"publish","type":"post","link":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/","title":{"rendered":"<strong>Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen.<\/strong>"},"content":{"rendered":"\n<p>Die Ank\u00fcndigungen f\u00fcr den Jahrgang 2023 der International Motor Show Luxembourg, dem unumg\u00e4nglichen Auto- und Motorradevent zum Jahresende in den Hallen der LuxExpo, das am Freitag, den 10., Samstag, den 11. und Sonntag, den 12. November stattfindet, \u00fcberschlagen sich. Nach Porsche und den Feierlichkeiten zum 75-j\u00e4hrigen Jubil\u00e4um der Marke und dem 60-j\u00e4hrigen Jubil\u00e4um des legend\u00e4ren 911, wird nun Mercedes-Benz an der Spitze des Plakats stehen, wobei die Merbag-Gruppe allgegenw\u00e4rtig ist.<\/p>\n\n\n\n<p>Das Ziel der Sternenmarke ist es, au\u00dfergew\u00f6hnliche Fahrzeuge zu pr\u00e4sentieren, wie z. B. die sportlichen Modelle der Mercedes-AMG-Reihe. Um dies zu unterstreichen, werden mehrere Rennwagen wie der Mercedes-AMG GT3 und GT4 ausgestellt.<\/p>\n\n\n\n<p>\u00ab&nbsp;Seit ihrer Gr\u00fcndung hat die International Motor Show Luxembourg immer Fans von Sport- und Rennfahrzeugen angezogen&nbsp;\u00bb, kommentiert Jean-Fran\u00e7ois Elst im Namen von Pole Position, dem Organisator der IMS.&nbsp;\u00ab&nbsp;Merbag Luxembourg hat perfekt verstanden, wie wichtig es ist, auf die Karte Sport und Wettbewerb zu spielen, und so wird die gesamte Veranstaltung von der Allgegenwart der Marke mit dem Stern und der Pr\u00e4sentation von in vielerlei Hinsicht au\u00dfergew\u00f6hnlichen Fahrzeugen profitieren k\u00f6nnen\u201d.<\/p>\n\n\n\n<p>Was wirklich nichts verdibt, ist, dass Merbag Luxemburg in den n\u00e4chsten Wochen den Schleier \u00fcber eine sehr sch\u00f6ne \u00dcberraschung heben m\u00fcsste.&nbsp;Wait and see.<\/p>\n\n\n\n<p>Es bleibt Ihnen also nichts anderes \u00fcbrig, als Freitag, den 10., Samstag, den 11. Und Sonntag, den 12. November in Ihrem Kalender hervorzuheben, um auf keinen Fall eine Veranstaltung zu verpassen, die prestigetr\u00e4chtiger und innovativer wird als je zuvor&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Ank\u00fcndigungen f\u00fcr den Jahrgang 2023 der International Motor Show Luxembourg, dem unumg\u00e4nglichen Auto- und Motorradevent zum Jahresende in den [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2415,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[52],"tags":[],"class_list":["post-2419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fassung-2023"],"acf":{"show_group":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen. - Motor Show<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen. - Motor Show\" \/>\n<meta property=\"og:description\" content=\"Die Ank\u00fcndigungen f\u00fcr den Jahrgang 2023 der International Motor Show Luxembourg, dem unumg\u00e4nglichen Auto- und Motorradevent zum Jahresende in den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/\" \/>\n<meta property=\"og:site_name\" content=\"Motor Show\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-27T13:26:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-27T13:26:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/motorshow.lu\/wp-content\/uploads\/sites\/2\/image010-1024x425.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"client\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"client\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/\"},\"author\":{\"name\":\"client\",\"@id\":\"https:\\\/\\\/motorshow.lu\\\/#\\\/schema\\\/person\\\/f869f197289e6a86361c833c1d0d95b5\"},\"headline\":\"Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen.\",\"datePublished\":\"2023-07-27T13:26:44+00:00\",\"dateModified\":\"2023-07-27T13:26:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/\"},\"wordCount\":265,\"image\":{\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/motorshow.lu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/image010.png\",\"articleSection\":[\"Fassung 2023\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/\",\"url\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/\",\"name\":\"Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen. - Motor Show\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/motorshow.lu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/motorshow.lu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/image010.png\",\"datePublished\":\"2023-07-27T13:26:44+00:00\",\"dateModified\":\"2023-07-27T13:26:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/motorshow.lu\\\/#\\\/schema\\\/person\\\/f869f197289e6a86361c833c1d0d95b5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/motorshow.lu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/image010.png\",\"contentUrl\":\"https:\\\/\\\/motorshow.lu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/image010.png\",\"width\":2081,\"height\":863},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/fassung-2023\\\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/motorshow.lu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/motorshow.lu\\\/#website\",\"url\":\"https:\\\/\\\/motorshow.lu\\\/\",\"name\":\"Motor Show\",\"description\":\"Un site utilisant Les sites de DG Sport\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/motorshow.lu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/motorshow.lu\\\/#\\\/schema\\\/person\\\/f869f197289e6a86361c833c1d0d95b5\",\"name\":\"client\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0de661745071daff296a69510a88dd6ff40167a4a7f4158f09a3680fab567f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0de661745071daff296a69510a88dd6ff40167a4a7f4158f09a3680fab567f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0de661745071daff296a69510a88dd6ff40167a4a7f4158f09a3680fab567f6?s=96&d=mm&r=g\",\"caption\":\"client\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen. - Motor Show","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/","og_locale":"de_DE","og_type":"article","og_title":"Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen. - Motor Show","og_description":"Die Ank\u00fcndigungen f\u00fcr den Jahrgang 2023 der International Motor Show Luxembourg, dem unumg\u00e4nglichen Auto- und Motorradevent zum Jahresende in den [&hellip;]","og_url":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/","og_site_name":"Motor Show","article_published_time":"2023-07-27T13:26:44+00:00","article_modified_time":"2023-07-27T13:26:45+00:00","og_image":[{"width":1024,"height":425,"url":"https:\/\/motorshow.lu\/wp-content\/uploads\/sites\/2\/image010-1024x425.png","type":"image\/png"}],"author":"client","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"client","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/#article","isPartOf":{"@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/"},"author":{"name":"client","@id":"https:\/\/motorshow.lu\/#\/schema\/person\/f869f197289e6a86361c833c1d0d95b5"},"headline":"Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen.","datePublished":"2023-07-27T13:26:44+00:00","dateModified":"2023-07-27T13:26:45+00:00","mainEntityOfPage":{"@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/"},"wordCount":265,"image":{"@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/#primaryimage"},"thumbnailUrl":"https:\/\/motorshow.lu\/wp-content\/uploads\/sites\/2\/image010.png","articleSection":["Fassung 2023"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/","url":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/","name":"Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen. - Motor Show","isPartOf":{"@id":"https:\/\/motorshow.lu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/#primaryimage"},"image":{"@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/#primaryimage"},"thumbnailUrl":"https:\/\/motorshow.lu\/wp-content\/uploads\/sites\/2\/image010.png","datePublished":"2023-07-27T13:26:44+00:00","dateModified":"2023-07-27T13:26:45+00:00","author":{"@id":"https:\/\/motorshow.lu\/#\/schema\/person\/f869f197289e6a86361c833c1d0d95b5"},"breadcrumb":{"@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/#primaryimage","url":"https:\/\/motorshow.lu\/wp-content\/uploads\/sites\/2\/image010.png","contentUrl":"https:\/\/motorshow.lu\/wp-content\/uploads\/sites\/2\/image010.png","width":2081,"height":863},{"@type":"BreadcrumbList","@id":"https:\/\/motorshow.lu\/de\/fassung-2023\/merbag-luxembourg-wird-amg-und-den-rennsport-in-den-mittelpunkt-stellen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/motorshow.lu\/de\/"},{"@type":"ListItem","position":2,"name":"Merbag Luxembourg wird AMG und den Rennsport in den Mittelpunkt stellen."}]},{"@type":"WebSite","@id":"https:\/\/motorshow.lu\/#website","url":"https:\/\/motorshow.lu\/","name":"Motor Show","description":"Un site utilisant Les sites de DG Sport","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/motorshow.lu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/motorshow.lu\/#\/schema\/person\/f869f197289e6a86361c833c1d0d95b5","name":"client","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d0de661745071daff296a69510a88dd6ff40167a4a7f4158f09a3680fab567f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0de661745071daff296a69510a88dd6ff40167a4a7f4158f09a3680fab567f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0de661745071daff296a69510a88dd6ff40167a4a7f4158f09a3680fab567f6?s=96&d=mm&r=g","caption":"client"}}]}},"_links":{"self":[{"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/posts\/2419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/comments?post=2419"}],"version-history":[{"count":0,"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/posts\/2419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/media\/2415"}],"wp:attachment":[{"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/media?parent=2419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/categories?post=2419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/motorshow.lu\/de\/wp-json\/wp\/v2\/tags?post=2419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}